{"id":1076,"date":"2018-02-01T15:57:21","date_gmt":"2018-02-01T12:57:21","guid":{"rendered":"http:\/\/univela.local\/home\/"},"modified":"2020-03-19T10:37:15","modified_gmt":"2020-03-19T07:37:15","slug":"main","status":"publish","type":"page","link":"https:\/\/univela-morocco.com\/es\/","title":{"rendered":"Main"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1076","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exportaciones de Marruecos. Gran empresa exportadora-importadora Univela Morocco<\/title>\n<meta name=\"description\" content=\"Somos un importante proveedor de pescado, mariscos, verduras, frutas y otros productos de Marruecos para usted. Exportamos productos a granjas en cualquier pa\u00eds\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univela-morocco.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exportaciones de Marruecos. Gran empresa exportadora-importadora Univela Morocco\" \/>\n<meta property=\"og:description\" content=\"Somos un importante proveedor de pescado, mariscos, verduras, frutas y otros productos de Marruecos para usted. Exportamos productos a granjas en cualquier pa\u00eds\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univela-morocco.com\/es\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-19T07:37:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.univela-morocco.com\/es\/\",\"url\":\"https:\/\/www.univela-morocco.com\/es\/\",\"name\":\"Exportaciones de Marruecos. Gran empresa exportadora-importadora Univela Morocco\",\"isPartOf\":{\"@id\":\"https:\/\/www.univela-morocco.com\/es\/#website\"},\"datePublished\":\"2018-02-01T12:57:21+00:00\",\"dateModified\":\"2020-03-19T07:37:15+00:00\",\"description\":\"Somos un importante proveedor de pescado, mariscos, verduras, frutas y otros productos de Marruecos para usted. Exportamos productos a granjas en cualquier pa\u00eds\",\"breadcrumb\":{\"@id\":\"https:\/\/www.univela-morocco.com\/es\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.univela-morocco.com\/es\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.univela-morocco.com\/es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.univela-morocco.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Main\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.univela-morocco.com\/es\/#website\",\"url\":\"https:\/\/www.univela-morocco.com\/es\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.univela-morocco.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exportaciones de Marruecos. Gran empresa exportadora-importadora Univela Morocco","description":"Somos un importante proveedor de pescado, mariscos, verduras, frutas y otros productos de Marruecos para usted. Exportamos productos a granjas en cualquier pa\u00eds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univela-morocco.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Exportaciones de Marruecos. Gran empresa exportadora-importadora Univela Morocco","og_description":"Somos un importante proveedor de pescado, mariscos, verduras, frutas y otros productos de Marruecos para usted. Exportamos productos a granjas en cualquier pa\u00eds","og_url":"https:\/\/www.univela-morocco.com\/es\/","article_modified_time":"2020-03-19T07:37:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.univela-morocco.com\/es\/","url":"https:\/\/www.univela-morocco.com\/es\/","name":"Exportaciones de Marruecos. Gran empresa exportadora-importadora Univela Morocco","isPartOf":{"@id":"https:\/\/www.univela-morocco.com\/es\/#website"},"datePublished":"2018-02-01T12:57:21+00:00","dateModified":"2020-03-19T07:37:15+00:00","description":"Somos un importante proveedor de pescado, mariscos, verduras, frutas y otros productos de Marruecos para usted. Exportamos productos a granjas en cualquier pa\u00eds","breadcrumb":{"@id":"https:\/\/www.univela-morocco.com\/es\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univela-morocco.com\/es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.univela-morocco.com\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.univela-morocco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Main"}]},{"@type":"WebSite","@id":"https:\/\/www.univela-morocco.com\/es\/#website","url":"https:\/\/www.univela-morocco.com\/es\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univela-morocco.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/pages\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/comments?post=1076"}],"version-history":[{"count":4,"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/pages\/1076\/revisions"}],"predecessor-version":[{"id":2971,"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/pages\/1076\/revisions\/2971"}],"wp:attachment":[{"href":"https:\/\/univela-morocco.com\/es\/wp-json\/wp\/v2\/media?parent=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}